{"id":306,"date":"2021-08-09T09:24:38","date_gmt":"2021-08-09T12:24:38","guid":{"rendered":"http:\/\/www.ceciliademedeiros.com.ar\/?p=306"},"modified":"2021-08-23T13:22:12","modified_gmt":"2021-08-23T16:22:12","slug":"marina-waisman","status":"publish","type":"post","link":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/afuera\/marina-waisman\/","title":{"rendered":"CIUDAD UNIVERSITARIA &#8211; MARINA WAISMAN"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"773\" height=\"1024\" src=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-773x1024.jpg\" alt=\"\" data-id=\"309\" data-link=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/afuera\/marina-waisman\/attachment\/1-2\/\" class=\"wp-image-309\" srcset=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-773x1024.jpg 773w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-227x300.jpg 227w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-768x1017.jpg 768w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-1600x2119.jpg 1600w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-1160x1536.jpg 1160w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-1547x2048.jpg 1547w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-1568x2076.jpg 1568w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-scaled.jpg 1933w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-684x1024.jpg\" alt=\"\" data-id=\"310\" data-link=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/afuera\/marina-waisman\/attachment\/fotosmarina-2\/\" class=\"wp-image-310\" srcset=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-684x1024.jpg 684w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-200x300.jpg 200w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-768x1150.jpg 768w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-1600x2397.jpg 1600w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-1025x1536.jpg 1025w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-1367x2048.jpg 1367w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-1568x2349.jpg 1568w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-2-scaled.jpg 1709w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-684x1024.jpg\" alt=\"\" data-id=\"312\" data-full-url=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-scaled.jpg\" data-link=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/afuera\/marina-waisman\/attachment\/fotosmarina-43\/\" class=\"wp-image-312\" srcset=\"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-684x1024.jpg 684w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-200x300.jpg 200w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-768x1150.jpg 768w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-1600x2397.jpg 1600w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-1025x1536.jpg 1025w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-1367x2048.jpg 1367w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-1568x2349.jpg 1568w, https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/fotosMarina-43-scaled.jpg 1709w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Marina Waisman fue una arquitecta argentina, reconocida a nivel iberoamericano por sus aportes al campo de la cr\u00edtica arquitect\u00f3nica. Su apellido de nacimiento era Kitroser y ella firmaba con su apellido de casada, Waisman. Nacida en Buenos Aires en el a\u00f1o 1920 y fallecida en R\u00edo Cuarto en el a\u00f1o 1997, se form\u00f3 en la Universidad Nacional de C\u00f3rdoba, desarrollando all\u00ed y en la Universidad Cat\u00f3lica de C\u00f3rdoba su carrera docente.&nbsp;<\/p>\n\n\n\n<p>Marina se gradu\u00f3 en 1945, cuando Arquitectura a\u00fan se estudiaba junto con las carreras de Ingenier\u00eda y fue la \u00fanica mujer de su promoci\u00f3n. Solo dos arquitectas se hab\u00edan recibido antes que ella: N\u00e9lida Azpilicueta en 1937 y L\u00edbera Carmignani en 1942. Escribe Marina en el art\u00edculo \u201c<a href=\"https:\/\/undiaunaarquitecta.files.wordpress.com\/2015\/05\/marina-waisman-la-mujer-en-la-arquitectura_031.pdf\">La mujer en la arquitectura<\/a>\u201d de 1969 que \u201c(&#8230;) Las mujeres se comienzan a incorporar a las universidades, la administraci\u00f3n p\u00fablica y los equipos de concursos hacia los a\u00f1os 60 cuando comienza adem\u00e1s a incrementarse el n\u00famero de alumnas de la carrera (&#8230;) Todo esto no ha sido ganado sin esfuerzo. En general, la mujer como profesional tiene comienzos mucho m\u00e1s dif\u00edciles que el hombre y el abrirse paso en la profesi\u00f3n suele resultar, en ocasiones, realmente arduo. Es muy frecuente que la mujer deba demostrar una capacidad indiscutiblemente mayor que la de sus competidores masculinos para ocupar un lugar cualquiera en la profesi\u00f3n.\u201d<\/p>\n\n\n\n<p>La problem\u00e1tica del g\u00e9nero form\u00f3 parte de su mirada cr\u00edtica, reflej\u00e1ndose en su producci\u00f3n hasta sus \u00faltimos a\u00f1os. A fines de 1995 la encontramos en el art\u00edculo \u201cSexo d\u00e9bil\u201d escribiendo sobre el cambio de rol de la mujer en su campo, destacando el trabajo de colegas como Lina Bo Bardi que dejaron su huella en la arquitectura contempor\u00e1nea.<\/p>\n\n\n\n<p><em>&#8220;&#8230;mirar a lo propio con ojos propios&#8221;<\/em><\/p>\n\n\n\n<p>Una de las marcas persistentes de la colonizaci\u00f3n en los pa\u00edses latinoamericanos ha sido la de estudiar a partir de categor\u00edas y herramientas del saber generadas en y para el contexto de los pa\u00edses centrales. Esto es algo se\u00f1alado frecuentemente en los espacios acad\u00e9micos, junto con el llamado a producir conocimientos situados, que respondan a la historia y las problem\u00e1ticas contempor\u00e1neas de cada regi\u00f3n. Pero mucho menos frecuente es que alguien pase de la palabra a la acci\u00f3n. Marina fue una de las que dio ese paso: el de crear instrumentos propios para el an\u00e1lisis de la arquitectura latinoamericana, ponerlos en pr\u00e1ctica en el trabajo sobre la ciudad y hacerlos circular en los espacios acad\u00e9micos, disputando las posiciones dominantes en el campo.<\/p>\n\n\n\n<p>En su art\u00edculo \u201cAutocr\u00edtica\u201d de 1998, Marina nos invita a \u201c(&#8230;) reconocer que los instrumentos de pensamiento que utilizamos no son neutros, sino que las preguntas orientan y califican las respuestas, [hay que] efectuar un ajustado an\u00e1lisis de ciertos instrumentos de pensamiento que, provenientes de los pa\u00edses \u00b4centrales\u00b4, han encerrado largamente la historiograf\u00eda de la arquitectura latinoamericana en l\u00edmites y pautas de valoraci\u00f3n que distorsionaban su significado.\u201d Y contin\u00faa, trazando el rumbo de su proyecto: &#8220;El esfuerzo principal se hizo, pues, para mirar lo propio con ojos propios (&#8230;) descubrir que el ordenamiento del desarrollo hist\u00f3rico latinoamericano deber\u00eda ser diferente del can\u00f3nicamente aceptado, que est\u00e1 referido al mundo europeo; intentar una definici\u00f3n de la ubicaci\u00f3n de la arquitectura latinoamericana en el concierto mundial. Y sobre todo, dejar formuladas las preguntas tendientes a comprender y evaluar la problem\u00e1tica arquitect\u00f3nica latinoamericana.\u201d.<\/p>\n\n\n\n<p>Este inter\u00e9s est\u00e1 presente desde su primer libro, \u201cLa estructura hist\u00f3rica del entorno\u201d, a cuya escritura se aboc\u00f3 tras decidir en 1970 apartarse de la tarea docente que ejerc\u00eda desde 1948 en la Universidad Nacional de C\u00f3rdoba, debido a los graves conflictos pol\u00edticos que atravesaban la universidad en ese momento.<\/p>\n\n\n\n<p>Su reflexi\u00f3n se continu\u00f3 a lo largo de su vida con la publicaci\u00f3n de otros libros, numerosos art\u00edculos en revistas internacionales de arquitectura y una dedicada tarea editorial, donde se destacan la direcci\u00f3n de los <em>Summarios<\/em> en la revista Summa de Buenos Aires y, tras el cierre de \u00e9sta, su continuidad en la serie <em>Cuadernos Summa \/ Nueva Visi\u00f3n<\/em> de la editorial Escala de Colombia.<\/p>\n\n\n\n<p>El reconocimiento a sus aportes a la arquitectura latinoamericana se reflej\u00f3 en actos como el otorgamiento en 1987 del Premio Am\u00e9rica de Historia y Preservaci\u00f3n del patrimonio de la Universidad Cat\u00f3lica de C\u00f3rdoba o su incorporaci\u00f3n como miembro de la Academia Nacional de Bellas Artes de la Argentina.<\/p>\n\n\n\n<p><em>[La arquitectura] \u201ccomo una urdimbre formada&nbsp;<\/em><\/p>\n\n\n\n<p><em>por tramas de significaci\u00f3n\u201d<\/em>.<\/p>\n\n\n\n<p>Quien recorre hoy la provincia de C\u00f3rdoba puede visitar una serie de sitios de Patrimonio Hist\u00f3rico cuya existencia, estado de conservaci\u00f3n y el rigor hist\u00f3rico de la misma no ser\u00edan posibles sin la investigaci\u00f3n, difusi\u00f3n y activismo de Marina y quienes trabajaron con ella. Entre estos sitios podemos destacar casonas hist\u00f3ricas como la del actual Centro Cultural Espa\u00f1a C\u00f3rdoba o el Museo Emilio Caraffa, edificaciones religiosas como el Convento de las Carmelitas Descalzas o la Capilla Dom\u00e9stica de la Iglesia de la Compa\u00f1\u00eda de Jes\u00fas y sitios relevantes del interior de la provincia, como la capilla de Candonga.<\/p>\n\n\n\n<p>La coherencia de Marina entre pensamiento y acci\u00f3n tiene un episodio significativo en 1970, cuando renuncia a la asesor\u00eda que realizaba en materia de arquitectura para la municipalidad de la ciudad de C\u00f3rdoba porque, pese a su firme oposici\u00f3n, se decidi\u00f3 demoler la casona del pintor Emiliano G\u00f3mez Clara, ubicada donde hoy se encuentra la Plaza de la Intendencia.<\/p>\n\n\n\n<p>Ese activismo, que daba cuenta de la continuidad que ella trazaba entre su vida personal y profesional, tambi\u00e9n tiene su postal cotidiana en los v\u00ednculos con su familia. Sus sobrinos la recuerdan ense\u00f1\u00e1ndoles canciones de la resistencia espa\u00f1ola en las reuniones familiares, donde ella tocaba la guitarra y cantaba. Marina estudi\u00f3 en el Conservatorio Provincial y toc\u00f3 el arpa con la Orquesta Sinf\u00f3nica de C\u00f3rdoba, camino que dej\u00f3 atr\u00e1s para dedicarse a la historia de la arquitectura. Una generaci\u00f3n m\u00e1s adelante, la recuerdan reuniendo a sus nietos en su casa para darles clases de historia del arte.<\/p>\n\n\n\n<p>Su conciencia sobre el patrimonio arquitect\u00f3nico como forma presente de la historia la llev\u00f3 a crear espacios para su estudio, investigaci\u00f3n y promoci\u00f3n. La primera de estas instituciones fue el IIDEHA (Instituto Interuniversitario de Historia de Arquitectura), creado junto a junto a Enrico Tedeschi y Francisco Bullrich en Tucum\u00e1n a fines de la d\u00e9cada de 1950. Al incorporarse en 1974 a la Universidad Cat\u00f3lica de C\u00f3rdoba, form\u00f3 el Instituto de Historia y Preservaci\u00f3n del Patrimonio, hoy denominado Instituto Marina Waisman, que fue la primera carrera de arquitectos especialistas en historia de la arquitectura y primer posgrado de la ciudad de C\u00f3rdoba. Fue con el grupo de trabajo formado all\u00ed que intervinieron en obras patrimoniales de la ciudad y elaboraron en 1979 el primer cat\u00e1logo del Patrimonio arquitect\u00f3nico urbano de la ciudad, que hoy tiene una actualizaci\u00f3n anual por parte de la municipalidad.<\/p>\n\n\n\n<p>La amplitud del proyecto historiogr\u00e1fico de Marina rebasaba tanto los espacios como su tiempo. En su libro \u201cEl interior de la historia\u201d de 1990 afirma que \u201cAbundan los trabajos parciales y a\u00fan puntuales, pero faltaba esa visi\u00f3n actual del conjunto. En los a\u00f1os recientes se han multiplicado las investigaciones, y, al menos en la Argentina, se nota un creciente inter\u00e9s en los estudios hist\u00f3ricos por parte de los arquitectos, especialmente de las nuevas generaciones. En su mayor\u00eda, sin embargo, se ven obligados a ser algo as\u00ed como francotiradores de la cultura, pues no existen instituciones universitarias o estatales que cuenten con los fondos necesarios para establecer programas permanentes y de la necesaria amplitud. Una labor como la que cumpli\u00f3 Sir Nikolaus Pevsner &#8211; el inventario de toda la arquitectura hist\u00f3rica inglesa &#8211; permanece, para nosotros, en el reino de la utop\u00eda\u201d.<\/p>\n\n\n\n<p>La conformaci\u00f3n de grupos y espacios de discusi\u00f3n fue una constante en su vida. Sus amistades resaltan la relevancia de las tertulias que se organizaban en la casa de Marina como un espacio de enriquecimiento y germen de nuevos proyectos, donde ella compart\u00eda sus lecturas, sus desvelos, sus hallazgos y sus preguntas.<\/p>\n\n\n\n<p>Marina tuvo una intensa actividad en los Seminarios de Arquitectura Latinoamericana que se iniciaron en 1985 en Buenos Aires y contin\u00faan hasta la fecha. Este grupo fue un n\u00facleo de discusi\u00f3n sobre el impacto del movimiento posmoderno en nuestras ciudades, la destrucci\u00f3n del patrimonio y los modos propios de aproximaci\u00f3n a estas problem\u00e1ticas.&nbsp;<\/p>\n\n\n\n<p>La obra de Marina registra el impulso hacia un cambio de paradigma sobre la arqueolog\u00eda patrimonial, que desarticula la visi\u00f3n sobre el trazado urbano basada en la producci\u00f3n de narraciones carentes de pasado y conflicto, hacia una b\u00fasqueda de herramientas de cr\u00edtica y redefiniciones de las ret\u00f3ricas de valor que permitan entender a la arquitectura a partir de la relaci\u00f3n con su contexto, geogr\u00e1fico y temporal. Estas reflexiones se condensar\u00e1n principalmente en su \u00faltimo libro: \u201cLa arquitectura descentrada\u201d, de 1995.<\/p>\n\n\n\n<p>Dice Liliana Lolich en el art\u00edculo \u201cLas miradas de Marina Waisman\u201d que el llamado de Marina es a \u201cComprender la arquitectura actual en toda su complejidad, rechazando las simplificaciones reduccionistas, aceptando sus m\u00faltiples riquezas. Uno de sus \u00faltimos escritos pone el \u00e9nfasis en el contexto, superando la visi\u00f3n de los componentes urbanos como simple sumatoria de objetos sino \u2018como una urdimbre formada por tramas de significaci\u00f3n\u2019. De este modo, las relaciones adquieren mayor trascendencia que los objetos en s\u00ed mismos por lo cual no basta con conservar edificios vac\u00edos de significado\u201d.&nbsp;<\/p>\n\n\n\n<p>Marina abre la puerta a entender la arquitectura y el desarrollo urbano atravesados por la din\u00e1mica del mundo fragmentado de finales del SXX.<\/p>\n\n\n\n<p>Escribe al respecto en \u201cEl interior de la historia\u201d: \u201cLas condiciones de la difusi\u00f3n han cambiado radicalmente en el mundo contempor\u00e1neo, y tambi\u00e9n la relaci\u00f3n de poder entre las naciones del mundo (&#8230;). La aceleraci\u00f3n de la historia y de los cambios en la vida social, en las expectativas en los modos de vida; la multiplicaci\u00f3n en y el nuevo alcance de los medios de comunicaci\u00f3n, que han eliminado distancias y diferencias culturales en cuanto a la recepci\u00f3n de la informaci\u00f3n; los mecanismos de la sociedad de consumo, que alientan la renovaci\u00f3n constante de objetos y formas, decretando obsolescencias y proclamando nuevos valores que muy pronto, a su vez, caer\u00e1n bajo la ley del consumo, han dado como resultado que el car\u00e1cter creativo, positivo, enriquecedor de la difusi\u00f3n cultural quede muy a menudo sumergido bajo los aspectos negativos de una aceptaci\u00f3n pasiva y superficial, por la cual las nuevas formas se superponen a las formas culturales existentes sin entrar en \u00edntima conexi\u00f3n con ellas, simplemente sustituy\u00e9ndolas e interrumpiendo sus posibles desarrollos (&#8230;). Otro de los efectos perversos del poder de la informaci\u00f3n es el reduccionismo que opera en la transmisi\u00f3n de la arquitectura y, en \u00faltima instancia, en la arquitectura misma. Pues los medios de difusi\u00f3n, con su magn\u00edfica calidad gr\u00e1fica, reducen la arquitectura construida a una representaci\u00f3n recortada de todo contexto, bidimensional, elocuente por el impacto de su imagen -a menudo \u2018construida\u2019 por un h\u00e1bil fot\u00f3grafo-. Esta operaci\u00f3n reductiva asigna la apreciaci\u00f3n de la arquitectura a uno s\u00f3lo de los sentidos, el de la vista, dejando de lado toda la riqueza espacial, mat\u00e9rica, sonora, ambiental, etc. Pero a su vez este modo de apreciaci\u00f3n de la arquitectura alienta a m\u00e1s de un profesional a concebir su obra en t\u00e9rminos \u2018fotog\u00e9nicos\u2019, buscando efectos que quiz\u00e1 sean irrelevantes en la obra construida, pero que podr\u00eda realzar su presencia en las p\u00e1ginas impresas.\u201d<\/p>\n\n\n\n<p>Leer a Marina Waisman desde el presente es una invitaci\u00f3n a pensar las ciudades no s\u00f3lo definidas por trazados y formas, sino por afectos y experiencias de quienes las habitan. Una dimensi\u00f3n est\u00e9tica de la arquitectura como parte inseparable del ejercicio de lo sensible por parte de les cuerpes que la habitan y una dimensi\u00f3n cr\u00edtica asentada en la vigilancia epistemol\u00f3gica de esa relaci\u00f3n.<\/p>\n\n\n\n<p>Marina propone en \u201cEl interior de la historia\u201d que la resistencia ante la presi\u00f3n homogeneizadora del aparato de la sociedad global, no debe entenderse en t\u00e9rminos de un localismo estrecho o el congelamiento del desarrollo hist\u00f3rico. Su propuesta es que hay que dejar de lado las estructuras de los modelos centrales y emprender rumbos in\u00e9ditos.<\/p>\n\n\n\n<p>\u201cDivergir es desarrollar, a partir de lo que se es, lo que se puede llegar a ser (&#8230;) Desde el centro no puede verse a las m\u00e1rgenes como generadoras de proyectos, sino solo, quiz\u00e1s, como refugio. Desde las m\u00e1rgenes todo es -o deber\u00eda ser- proyecto.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MAY\u00d3LICA UBICADA EN EL CENTRO DE INVESTIGACIONES AC\u00daSTICAS Y LUMINOT\u00c9CNICAS &#8211; UNC.  CORDOBA, ARGENTINA.   <\/p>\n","protected":false},"author":1,"featured_media":309,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afuera"],"jetpack_featured_media_url":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-content\/uploads\/2021\/08\/1-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":7,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"predecessor-version":[{"id":319,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/posts\/306\/revisions\/319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/media\/309"}],"wp:attachment":[{"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ceciliademedeiros.com.ar\/wordpress\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}